{"id":1460,"date":"2025-08-20T18:06:06","date_gmt":"2025-08-20T16:06:06","guid":{"rendered":"https:\/\/mikadoadventure.fr\/?page_id=1460"},"modified":"2026-04-08T14:51:34","modified_gmt":"2026-04-08T12:51:34","slug":"purpose-commitment","status":"publish","type":"page","link":"https:\/\/mikadoadventure.fr\/en\/purpose-commitment\/","title":{"rendered":"Purpose &#038; commitment"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":8,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1460","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Purpose &amp; commitment - Mikado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mikadoadventure.fr\/en\/purpose-commitment\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Purpose &amp; commitment - Mikado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mikadoadventure.fr\/en\/purpose-commitment\/\" \/>\n<meta property=\"og:site_name\" content=\"Mikado\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mikadoadventure\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-08T12:51:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mikadoadventure.fr\\\/en\\\/purpose-commitment\\\/\",\"url\":\"https:\\\/\\\/mikadoadventure.fr\\\/en\\\/purpose-commitment\\\/\",\"name\":\"Purpose & commitment - Mikado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mikadoadventure.fr\\\/en\\\/#website\"},\"datePublished\":\"2025-08-20T16:06:06+00:00\",\"dateModified\":\"2026-04-08T12:51:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mikadoadventure.fr\\\/en\\\/purpose-commitment\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mikadoadventure.fr\\\/en\\\/purpose-commitment\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mikadoadventure.fr\\\/en\\\/purpose-commitment\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/mikadoadventure.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Purpose &#038; commitment\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mikadoadventure.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mikadoadventure.fr\\\/en\\\/\",\"name\":\"Mikado Adventure\",\"description\":\"Le s\u00e9minaire responsable en terres m\u00e9connues | Embarquez vos \u00e9quipes pour une exp\u00e9rience en pleine nature\",\"publisher\":{\"@id\":\"https:\\\/\\\/mikadoadventure.fr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mikadoadventure.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mikadoadventure.fr\\\/en\\\/#organization\",\"name\":\"Mikado Adventure\",\"url\":\"https:\\\/\\\/mikadoadventure.fr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mikadoadventure.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mikadoadventure.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Mikado.png\",\"contentUrl\":\"https:\\\/\\\/mikadoadventure.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo_Mikado.png\",\"width\":176,\"height\":44,\"caption\":\"Mikado Adventure\"},\"image\":{\"@id\":\"https:\\\/\\\/mikadoadventure.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mikadoadventure\",\"https:\\\/\\\/www.instagram.com\\\/mikado_adventure_\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Purpose & commitment - Mikado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mikadoadventure.fr\/en\/purpose-commitment\/","og_locale":"en_US","og_type":"article","og_title":"Purpose & commitment - Mikado","og_url":"https:\/\/mikadoadventure.fr\/en\/purpose-commitment\/","og_site_name":"Mikado","article_publisher":"https:\/\/www.facebook.com\/mikadoadventure","article_modified_time":"2026-04-08T12:51:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mikadoadventure.fr\/en\/purpose-commitment\/","url":"https:\/\/mikadoadventure.fr\/en\/purpose-commitment\/","name":"Purpose & commitment - Mikado","isPartOf":{"@id":"https:\/\/mikadoadventure.fr\/en\/#website"},"datePublished":"2025-08-20T16:06:06+00:00","dateModified":"2026-04-08T12:51:34+00:00","breadcrumb":{"@id":"https:\/\/mikadoadventure.fr\/en\/purpose-commitment\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mikadoadventure.fr\/en\/purpose-commitment\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mikadoadventure.fr\/en\/purpose-commitment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/mikadoadventure.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Purpose &#038; commitment"}]},{"@type":"WebSite","@id":"https:\/\/mikadoadventure.fr\/en\/#website","url":"https:\/\/mikadoadventure.fr\/en\/","name":"Mikado Adventure","description":"Le s\u00e9minaire responsable en terres m\u00e9connues | Embarquez vos \u00e9quipes pour une exp\u00e9rience en pleine nature","publisher":{"@id":"https:\/\/mikadoadventure.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mikadoadventure.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mikadoadventure.fr\/en\/#organization","name":"Mikado Adventure","url":"https:\/\/mikadoadventure.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mikadoadventure.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mikadoadventure.fr\/wp-content\/uploads\/2026\/03\/Logo_Mikado.png","contentUrl":"https:\/\/mikadoadventure.fr\/wp-content\/uploads\/2026\/03\/Logo_Mikado.png","width":176,"height":44,"caption":"Mikado Adventure"},"image":{"@id":"https:\/\/mikadoadventure.fr\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mikadoadventure","https:\/\/www.instagram.com\/mikado_adventure_"]}]}},"_links":{"self":[{"href":"https:\/\/mikadoadventure.fr\/en\/wp-json\/wp\/v2\/pages\/1460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mikadoadventure.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mikadoadventure.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mikadoadventure.fr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mikadoadventure.fr\/en\/wp-json\/wp\/v2\/comments?post=1460"}],"version-history":[{"count":0,"href":"https:\/\/mikadoadventure.fr\/en\/wp-json\/wp\/v2\/pages\/1460\/revisions"}],"wp:attachment":[{"href":"https:\/\/mikadoadventure.fr\/en\/wp-json\/wp\/v2\/media?parent=1460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}